{"id":84822,"date":"2024-05-21T17:33:47","date_gmt":"2024-05-21T15:33:47","guid":{"rendered":"https:\/\/www.proyectodona.org\/?page_id=84822"},"modified":"2024-09-23T11:53:24","modified_gmt":"2024-09-23T09:53:24","slug":"puntos-de-recogida","status":"publish","type":"page","link":"https:\/\/www.proyectodona.org\/index.php\/puntos-de-recogida\/","title":{"rendered":"Puntos de recogida"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(0,0,0,0.74)\u00bb background_image=\u00bbhttp:\/\/www.proyectodona.org\/wp-content\/uploads\/2024\/05\/Fondo-Banner-2.jpg\u00bb background_blend=\u00bbmultiply\u00bb custom_padding=\u00bb100px||100px||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.23.2&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb max_width=\u00bb1170px\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_margin_tablet=\u00bb0px||0px||false|false\u00bb custom_margin_phone=\u00bb100px||0px||false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbtop\u00bb animation_intensity_slide=\u00bb4%\u00bb animation_speed_curve=\u00bbease\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_icon font_icon=\u00bb&#xf111;||fa||900&#8243; icon_width=\u00bb30px\u00bb align=\u00bbleft\u00bb icon_width_tablet=\u00bb30px\u00bb icon_width_phone=\u00bb20px\u00bb icon_width_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.23.2&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px|10px|0px|90px|false|false\u00bb custom_margin_tablet=\u00bb|||165px|false|false\u00bb custom_margin_phone=\u00bb0px|10px|0px|3px|false|false\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb custom_css_main_element=\u00bbdisplay:inline-block;\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][et_pb_icon font_icon=\u00bb&#xf111;||fa||900&#8243; icon_width=\u00bb30px\u00bb align=\u00bbleft\u00bb icon_width_tablet=\u00bb30px\u00bb icon_width_phone=\u00bb20px\u00bb icon_width_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb custom_css_main_element=\u00bbdisplay:inline-block;\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][et_pb_text content_tablet=\u00bb<\/p>\n<h2>Asociaci\u00f3n m\u00e1s que ayuda y reciclaje<\/h2>\n<p>\u00bb content_phone=\u00bb<\/p>\n<h2>Asociaci\u00f3n m\u00e1s que ayuda y reciclaje<\/h2>\n<p>\u00bb content_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbOutfit|700||on|||||\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_font_size=\u00bb102px\u00bb header_letter_spacing=\u00bb10px\u00bb header_line_height=\u00bb1.1em\u00bb header_2_font=\u00bbOutfit|700|||||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_2_text_color=\u00bb#FFFFFF\u00bb header_2_font_size=\u00bb24px\u00bb header_2_letter_spacing=\u00bb2px\u00bb custom_margin=\u00bb-2px||0px||false|false\u00bb custom_margin_tablet=\u00bb0px||0px||false|false\u00bb custom_margin_phone=\u00bb0px||0px||false|false\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb header_font_size_tablet=\u00bb62px\u00bb header_font_size_phone=\u00bb40px\u00bb header_font_size_last_edited=\u00bbon|tablet\u00bb header_letter_spacing_tablet=\u00bb5px\u00bb header_letter_spacing_phone=\u00bb3px\u00bb header_letter_spacing_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Asociaci\u00f3n m\u00e1s que ayuda y reciclaje<\/h2>\n<p>[\/et_pb_text][et_pb_text content_tablet=\u00bb<\/p>\n<h1>Proyecto Dona<\/h1>\n<h1><a href=%22#%22><\/a><\/h1>\n<p>\u00bb content_phone=\u00bb<\/p>\n<h1>Proyecto <span style=%22color: #e5097f;%22>Dona<\/span><\/h1>\n<p>\u00bb content_last_edited=\u00bbon|tablet\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbOutfit|700||on|||||\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_font_size=\u00bb80px\u00bb header_letter_spacing=\u00bb10px\u00bb header_line_height=\u00bb1.1em\u00bb custom_margin=\u00bb-2px||0px||false|false\u00bb custom_margin_tablet=\u00bb0px||0px||false|false\u00bb custom_margin_phone=\u00bb0px||0px||false|false\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb header_font_size_tablet=\u00bb62px\u00bb header_font_size_phone=\u00bb40px\u00bb header_font_size_last_edited=\u00bbon|tablet\u00bb header_letter_spacing_tablet=\u00bb5px\u00bb header_letter_spacing_phone=\u00bb3px\u00bb header_letter_spacing_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>PUNTOS DE RECOGIDA<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|tablet\u00bb module_id=\u00bbPuntosRecogida\u00bb _builder_version=\u00bb4.23.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#000000&#8243; custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb50px||1px||false|false\u00bb custom_padding_tablet=\u00bb0px||0px||false|false\u00bb custom_padding_phone=\u00bb0px||0px||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb custom_margin=\u00bb0px||40px||false|false\u00bb custom_padding=\u00bb40px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bbOutfit|700|||||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_2_text_color=\u00bb#FFFFFF\u00bb header_2_font_size=\u00bb51px\u00bb header_2_line_height=\u00bb1.2em\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb header_2_font_size_tablet=\u00bb51px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>PROPUESTA DE RECOGIDA<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbManrope||||||||\u00bb text_text_color=\u00bbrgba(255,255,255,0.64)\u00bb text_font_size=\u00bb15px\u00bb text_letter_spacing=\u00bb1px\u00bb text_line_height=\u00bb2em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb0px||30px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>El Objeto del presente Servicio es la recogida de residuos textiles en distintos puntos de un termino municipal. Esto implica una organizaci\u00f3n eficiente para llegar de una forma eficaz que nos haga cumplir con los objetivos del Servicio.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|tablet\u00bb _builder_version=\u00bb4.23.2&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb max_width=\u00bb1170px\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||100px||false|false\u00bb custom_padding_tablet=\u00bb||0px||false|false\u00bb custom_padding_phone=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|||87px|false|false\u00bb custom_padding_tablet=\u00bb|||0px|false|false\u00bb custom_padding_phone=\u00bb|||0px|false|false\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbright\u00bb animation_intensity_slide=\u00bb3%\u00bb animation_speed_curve=\u00bbease\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bbOutfit|700|||||||\u00bb header_2_text_align=\u00bbleft\u00bb header_2_text_color=\u00bb#FFFFFF\u00bb header_2_font_size=\u00bb51px\u00bb header_2_line_height=\u00bb1.2em\u00bb custom_margin=\u00bb0px||19px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb header_2_font_size_tablet=\u00bb51px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Horario <span style=\"color: #e5097f;\">de trabajo<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbManrope||||||||\u00bb text_text_color=\u00bbrgba(255,255,255,0.64)\u00bb text_font_size=\u00bb15px\u00bb text_letter_spacing=\u00bb1px\u00bb text_line_height=\u00bb2em\u00bb custom_margin=\u00bb0px||12px||false|false\u00bb custom_padding=\u00bb0px|70px|0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>El horario de trabajo se fijar\u00e1 en jornada partida de lunes a viernes de 8:00- 14:00 y de 15:00-17:00, turn\u00e1ndose en guardias localizadas de 24 horas para actuaciones de emergencia.<\/p>\n<p>[\/et_pb_text][et_pb_code admin_label=\u00bbblurm img border fix\u00bb _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<style><!-- [et_pb_line_break_holder] -->  .et_pb_main_blurb_image > span > img {<!-- [et_pb_line_break_holder] -->    border-radius:unset;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><\/style>\n<p>[\/et_pb_code][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbleft\u00bb animation_intensity_slide=\u00bb3%\u00bb animation_speed_curve=\u00bbease\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/www.proyectodona.org\/wp-content\/uploads\/2024\/05\/Horario-proyecto-dona-mucho-mas-que-ayuda.jpg\u00bb title_text=\u00bbHorario &#8211; proyecto dona mucho mas que ayuda\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; _builder_version=\u00bb4.23.2&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb max_width=\u00bb1170px\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||100px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbleft\u00bb animation_intensity_slide=\u00bb3%\u00bb animation_speed_curve=\u00bbease\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/www.proyectodona.org\/wp-content\/uploads\/2024\/05\/Limpieza-del-entorno-exterior.jpg\u00bb title_text=\u00bbLimpieza del entorno exterior\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|||87px|false|false\u00bb custom_padding_tablet=\u00bb|||0px|false|false\u00bb custom_padding_phone=\u00bb|||0px|false|false\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbright\u00bb animation_intensity_slide=\u00bb3%\u00bb animation_speed_curve=\u00bbease\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.2&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bbOutfit|700|||||||\u00bb header_2_text_align=\u00bbleft\u00bb header_2_text_color=\u00bb#FFFFFF\u00bb header_2_font_size=\u00bb51px\u00bb header_2_line_height=\u00bb1.2em\u00bb custom_margin=\u00bb0px||19px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb header_2_font_size_tablet=\u00bb51px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Proceso de <span style=\"color: #e5097f;\">Trabajo<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbManrope||||||||\u00bb text_text_color=\u00bbrgba(255,255,255,0.64)\u00bb text_font_size=\u00bb15px\u00bb text_letter_spacing=\u00bb1px\u00bb text_line_height=\u00bb2em\u00bb custom_margin=\u00bb0px||12px||false|false\u00bb custom_padding=\u00bb0px|70px|0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Para recogida una vez definida la ubicaci\u00f3n de los contenedores se dise\u00f1ar\u00e1 una ruta de la cual obtendremos el tiempo estimado en traslados, a lo que hemos sumado 15 min por parada para vaciado de contenedor, cantidad suficiente de tiempo seg\u00fan nuestra experiencia para realizar descarga, as\u00ed como inspecci\u00f3n ocular tanto del entorno como del propio contenedor.<\/p>\n<p>Dentro de la planificaci\u00f3n se tendr\u00e1 en cuenta evitar viales de acceso al municipio a horas punta para no perjudicar al ciudadano, teniendo en cuenta zonas industriales en horario de incorporaci\u00f3n y salida, as\u00ed como centros escolares.<\/p>\n<p>[\/et_pb_text][et_pb_code admin_label=\u00bbblurm img border fix\u00bb _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<style><!-- [et_pb_line_break_holder] -->  .et_pb_main_blurb_image > span > img {<!-- [et_pb_line_break_holder] -->    border-radius:unset;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><\/style>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|tablet\u00bb _builder_version=\u00bb4.23.2&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb max_width=\u00bb1170px\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||100px||false|false\u00bb custom_padding_tablet=\u00bb||0px||false|false\u00bb custom_padding_phone=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|||87px|false|false\u00bb custom_padding_tablet=\u00bb|||0px|false|false\u00bb custom_padding_phone=\u00bb|||0px|false|false\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbright\u00bb animation_intensity_slide=\u00bb3%\u00bb animation_speed_curve=\u00bbease\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.2&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bbOutfit|700|||||||\u00bb header_2_text_align=\u00bbleft\u00bb header_2_text_color=\u00bb#FFFFFF\u00bb header_2_font_size=\u00bb51px\u00bb header_2_line_height=\u00bb1.2em\u00bb custom_margin=\u00bb0px||19px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb header_2_font_size_tablet=\u00bb51px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><span style=\"color: #e5097f;\">Contenedores<\/span> de recogida<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbManrope||||||||\u00bb text_text_color=\u00bbrgba(255,255,255,0.64)\u00bb text_font_size=\u00bb15px\u00bb text_letter_spacing=\u00bb1px\u00bb text_line_height=\u00bb2em\u00bb custom_margin=\u00bb0px||12px||false|false\u00bb custom_padding=\u00bb0px|70px|0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div class=\"MuiGrid-root MuiGrid-item MuiGrid-grid-xs-12\">\n<div class=\"MuiPaper-root MuiPaper-elevation0 MuiPaper-rounded\" id=\"section-card-21\">\n<div class=\"MuiGrid-root MuiGrid-container\">\n<div class=\"MuiGrid-root MuiGrid-item MuiGrid-grid-xs-12\">\n<div>\n<p class=\"MuiTypography-root MuiTypography-body1\">El modelo de contenedor utilizado por <span style=\"color: rgba(229, 9, 127, 0.64);\">ASOCIACI\u00d3N M\u00c1S QUE AYUDA<\/span> Son contenedores met\u00e1licos en forma de caja con una apertura basculante la cual se utilizan para introducir la ropa, est\u00e1n fabricados en chapa de 1,5mm reforzado con perfiles de acero en estructura y base. El interior est\u00e1 perfectamente sellado para proteger a las prendas y su almacenaje hasta el vaciado del mismo. La puerta trasera tiene un sistema de doble candado que refuerza su seguridad y hace muy complicado el hurto. Adem\u00e1s, est\u00e1n adaptados para ser transportados en carretilla o gr\u00faa.<\/p>\n<p class=\"MuiTypography-root MuiTypography-body1\"><span style=\"color: rgba(229, 9, 127, 0.64);\">\u2192\u00a0 <\/span>Los contenedores que utilizamos en la actualidad para la ejecuci\u00f3n de contratos similares tiene una <span style=\"color: rgba(229, 9, 127, 0.64);\">capacidad neta de carga de 1.635 litros<\/span>, siendo sus vol\u00famenes totales 2600 litros.<\/p>\n<p class=\"MuiTypography-root MuiTypography-body1\"><span style=\"color: rgba(229, 9, 127, 0.64);\">\u2192\u00a0 <\/span>El <span style=\"color: rgba(229, 9, 127, 0.64);\">sistema de abertura<\/span> cuenta con una compuerta. Este sistema dispone de un pasamanos que consigue que el proceso de apertura sea muy sencillo. As\u00ed como impedir el hurto de la ropa depositada.<\/p>\n<p class=\"MuiTypography-root MuiTypography-body1\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"MuiGrid-root MuiGrid-item MuiGrid-grid-xs-12\">\n<div class=\"MuiPaper-root MuiPaper-elevation0 MuiPaper-rounded\" id=\"section-card-22\">\n<div class=\"MuiGrid-root MuiGrid-container\">\n<div class=\"MuiGrid-root MuiGrid-item MuiGrid-grid-xs-12\">\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_code admin_label=\u00bbblurm img border fix\u00bb _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<style><!-- [et_pb_line_break_holder] -->  .et_pb_main_blurb_image > span > img {<!-- [et_pb_line_break_holder] -->    border-radius:unset;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><\/style>\n<p>[\/et_pb_code][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbleft\u00bb animation_intensity_slide=\u00bb3%\u00bb animation_speed_curve=\u00bbease\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttp:\/\/www.proyectodona.org\/wp-content\/uploads\/2024\/05\/Foto-gallery-9.png\u00bb title_text=\u00bbFoto gallery &#8211; 9&#8243; align=\u00bbright\u00bb align_tablet=\u00bbcenter\u00bb align_phone=\u00bbcenter\u00bb align_last_edited=\u00bbon|tablet\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb584px\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_margin_tablet=\u00bb0px||60px||false|false\u00bb custom_margin_phone=\u00bb||55px||false|false\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb filter_opacity=\u00bb60%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbManrope||||||||\u00bb text_text_color=\u00bbrgba(255,255,255,0.64)\u00bb text_font_size=\u00bb15px\u00bb text_line_height=\u00bb2em\u00bb text_orientation=\u00bbright\u00bb custom_margin=\u00bb|-90px|||true|false\u00bb custom_padding=\u00bb15px|85px||85px|false|true\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div class=\"MuiGrid-root MuiGrid-item MuiGrid-grid-xs-12\">\n<div class=\"MuiPaper-root MuiPaper-elevation0 MuiPaper-rounded\" id=\"section-card-5\">\n<div class=\"MuiGrid-root MuiGrid-container\">\n<div class=\"MuiGrid-root MuiGrid-item MuiGrid-grid-xs-12\">\n<div>\n<p class=\"MuiTypography-root MuiTypography-body1\">La experiencia nos dice, que el sistema es seguro, tanto para el usuario como para el residuo, teniendo instalados m\u00e1s de 360 ud de este modelo sin haber registrado ning\u00fan incidente.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"MuiGrid-root MuiGrid-item MuiGrid-grid-xs-12\">\n<div class=\"MuiPaper-root MuiPaper-elevation0 MuiPaper-rounded\" id=\"section-card-6\">\n<div class=\"MuiGrid-root MuiGrid-container\">\n<div class=\"MuiGrid-root MuiGrid-item MuiGrid-grid-xs-12\">\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#000000&#8243; custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb50px||50px||false|false\u00bb border_width_top=\u00bb1px\u00bb border_color_top=\u00bb#1a1a1a\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb max_width=\u00bb100%\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.22.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.23.2&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbManrope|800|||||||\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb179px\u00bb text_letter_spacing=\u00bb-3px\u00bb text_line_height=\u00bb1em\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb text_font_size_tablet=\u00bb100px\u00bb text_font_size_phone=\u00bb55px\u00bb text_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Proyecto <span style=\"color: #e5097f;\">Dona<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb module_id=\u00bbSegundasOportunidades\u00bb _builder_version=\u00bb4.23.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#000000&#8243; custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||1px||false|false\u00bb custom_padding_tablet=\u00bb0px||114px||false|false\u00bb custom_padding_phone=\u00bb0px||84px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.23.2&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb max_width=\u00bb570px\u00bb custom_margin=\u00bb0px||40px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_icon font_icon=\u00bb&#xf111;||fa||900&#8243; icon_width=\u00bb7px\u00bb _builder_version=\u00bb4.23.2&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px||15px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][et_pb_text _builder_version=\u00bb4.23.2&#8243; _module_preset=\u00bbdefault\u00bb header_4_font=\u00bbManrope|||on|||||\u00bb header_4_text_align=\u00bbcenter\u00bb header_4_text_color=\u00bb#5d5d5d\u00bb header_4_font_size=\u00bb14px\u00bb header_4_letter_spacing=\u00bb1.4px\u00bb header_4_line_height=\u00bb1.2em\u00bb custom_margin=\u00bb0px||-5px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Conseguimos darle<\/h4>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.23.2&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bbOutfit|700|||||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_2_text_color=\u00bb#FFFFFF\u00bb header_2_font_size=\u00bb51px\u00bb header_2_line_height=\u00bb1.2em\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb header_2_font_size_tablet=\u00bb51px\u00bb header_2_font_size_phone=\u00bb30px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>SEGUNDAS OPORTUNIDADES<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.23.2&#8243; _module_preset=\u00bbdefault\u00bb header_4_font=\u00bbManrope|||on|||||\u00bb header_4_text_align=\u00bbcenter\u00bb header_4_text_color=\u00bb#5d5d5d\u00bb header_4_font_size=\u00bb14px\u00bb header_4_letter_spacing=\u00bb1.4px\u00bb header_4_line_height=\u00bb1.2em\u00bb custom_margin=\u00bb0px||-5px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Resuelve tus dudas<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asociaci\u00f3n m\u00e1s que ayuda y reciclajePUNTOS DE RECOGIDAPROPUESTA DE RECOGIDAEl Objeto del presente Servicio es la recogida de residuos textiles en distintos puntos de un termino municipal. Esto implica una organizaci\u00f3n eficiente para llegar de una forma eficaz que nos haga cumplir con los objetivos del Servicio.Horario de trabajoEl horario de trabajo se fijar\u00e1 en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-84822","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Puntos de recogida - Proyecto Dona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proyectodona.org\/index.php\/puntos-de-recogida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Puntos de recogida - Proyecto Dona\" \/>\n<meta property=\"og:description\" content=\"Asociaci\u00f3n m\u00e1s que ayuda y reciclajePUNTOS DE RECOGIDAPROPUESTA DE RECOGIDAEl Objeto del presente Servicio es la recogida de residuos textiles en distintos puntos de un termino municipal. Esto implica una organizaci\u00f3n eficiente para llegar de una forma eficaz que nos haga cumplir con los objetivos del Servicio.Horario de trabajoEl horario de trabajo se fijar\u00e1 en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proyectodona.org\/index.php\/puntos-de-recogida\/\" \/>\n<meta property=\"og:site_name\" content=\"Proyecto Dona\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-23T09:53:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proyectodona.org\/index.php\/puntos-de-recogida\/\",\"url\":\"https:\/\/www.proyectodona.org\/index.php\/puntos-de-recogida\/\",\"name\":\"Puntos de recogida - Proyecto Dona\",\"isPartOf\":{\"@id\":\"http:\/\/www.proyectodona.org\/#website\"},\"datePublished\":\"2024-05-21T15:33:47+00:00\",\"dateModified\":\"2024-09-23T09:53:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.proyectodona.org\/index.php\/puntos-de-recogida\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proyectodona.org\/index.php\/puntos-de-recogida\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.proyectodona.org\/index.php\/puntos-de-recogida\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/www.proyectodona.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puntos de recogida\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.proyectodona.org\/#website\",\"url\":\"http:\/\/www.proyectodona.org\/\",\"name\":\"Proyecto Dona\",\"description\":\"Mucho m\u00e1s que ayuda\",\"publisher\":{\"@id\":\"http:\/\/www.proyectodona.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.proyectodona.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/www.proyectodona.org\/#organization\",\"name\":\"Proyecto Dona\",\"url\":\"http:\/\/www.proyectodona.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/www.proyectodona.org\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.proyectodona.org\/wp-content\/uploads\/2024\/07\/Logo-mucho-mas-que-ayuda-proyecto-dona.png\",\"contentUrl\":\"http:\/\/www.proyectodona.org\/wp-content\/uploads\/2024\/07\/Logo-mucho-mas-que-ayuda-proyecto-dona.png\",\"width\":481,\"height\":447,\"caption\":\"Proyecto Dona\"},\"image\":{\"@id\":\"http:\/\/www.proyectodona.org\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Puntos de recogida - Proyecto Dona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.proyectodona.org\/index.php\/puntos-de-recogida\/","og_locale":"es_ES","og_type":"article","og_title":"Puntos de recogida - Proyecto Dona","og_description":"Asociaci\u00f3n m\u00e1s que ayuda y reciclajePUNTOS DE RECOGIDAPROPUESTA DE RECOGIDAEl Objeto del presente Servicio es la recogida de residuos textiles en distintos puntos de un termino municipal. Esto implica una organizaci\u00f3n eficiente para llegar de una forma eficaz que nos haga cumplir con los objetivos del Servicio.Horario de trabajoEl horario de trabajo se fijar\u00e1 en [&hellip;]","og_url":"https:\/\/www.proyectodona.org\/index.php\/puntos-de-recogida\/","og_site_name":"Proyecto Dona","article_modified_time":"2024-09-23T09:53:24+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.proyectodona.org\/index.php\/puntos-de-recogida\/","url":"https:\/\/www.proyectodona.org\/index.php\/puntos-de-recogida\/","name":"Puntos de recogida - Proyecto Dona","isPartOf":{"@id":"http:\/\/www.proyectodona.org\/#website"},"datePublished":"2024-05-21T15:33:47+00:00","dateModified":"2024-09-23T09:53:24+00:00","breadcrumb":{"@id":"https:\/\/www.proyectodona.org\/index.php\/puntos-de-recogida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.proyectodona.org\/index.php\/puntos-de-recogida\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.proyectodona.org\/index.php\/puntos-de-recogida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/www.proyectodona.org\/"},{"@type":"ListItem","position":2,"name":"Puntos de recogida"}]},{"@type":"WebSite","@id":"http:\/\/www.proyectodona.org\/#website","url":"http:\/\/www.proyectodona.org\/","name":"Proyecto Dona","description":"Mucho m\u00e1s que ayuda","publisher":{"@id":"http:\/\/www.proyectodona.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.proyectodona.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/www.proyectodona.org\/#organization","name":"Proyecto Dona","url":"http:\/\/www.proyectodona.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/www.proyectodona.org\/#\/schema\/logo\/image\/","url":"http:\/\/www.proyectodona.org\/wp-content\/uploads\/2024\/07\/Logo-mucho-mas-que-ayuda-proyecto-dona.png","contentUrl":"http:\/\/www.proyectodona.org\/wp-content\/uploads\/2024\/07\/Logo-mucho-mas-que-ayuda-proyecto-dona.png","width":481,"height":447,"caption":"Proyecto Dona"},"image":{"@id":"http:\/\/www.proyectodona.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.proyectodona.org\/index.php\/wp-json\/wp\/v2\/pages\/84822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.proyectodona.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.proyectodona.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.proyectodona.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proyectodona.org\/index.php\/wp-json\/wp\/v2\/comments?post=84822"}],"version-history":[{"count":12,"href":"https:\/\/www.proyectodona.org\/index.php\/wp-json\/wp\/v2\/pages\/84822\/revisions"}],"predecessor-version":[{"id":85109,"href":"https:\/\/www.proyectodona.org\/index.php\/wp-json\/wp\/v2\/pages\/84822\/revisions\/85109"}],"wp:attachment":[{"href":"https:\/\/www.proyectodona.org\/index.php\/wp-json\/wp\/v2\/media?parent=84822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}